{"id":27024,"date":"2026-07-13T13:32:56","date_gmt":"2026-07-13T13:32:56","guid":{"rendered":"https:\/\/freightned.com\/vacature\/logistiek-warehouse-medewerker\/"},"modified":"2026-07-13T13:32:56","modified_gmt":"2026-07-13T13:32:56","slug":"logistiek-warehouse-medewerker","status":"publish","type":"vacature","link":"https:\/\/freightned.com\/nl\/vacature\/logistiek-warehouse-medewerker\/","title":{"rendered":"Logistiek \/ Warehouse Medewerker"},"content":{"rendered":"<h4>Wat ga je doen?<\/h4>\n<p>Tekst over de vacature.<\/p>\n","protected":false},"featured_media":0,"menu_order":3,"template":"","class_list":["post-27024","vacature","type-vacature","status-publish","hentry","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Logistiek \/ Warehouse Medewerker - freightned<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/freightned.com\/nl\/vacature\/logistiek-warehouse-medewerker\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Logistiek \/ Warehouse Medewerker - freightned\" \/>\n<meta property=\"og:description\" content=\"Wat ga je doen? Tekst over de vacature.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/freightned.com\/nl\/vacature\/logistiek-warehouse-medewerker\/\" \/>\n<meta property=\"og:site_name\" content=\"freightned\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/freightned.com\/vacature\/logistiek-warehouse-medewerker\/\",\"url\":\"https:\/\/freightned.com\/vacature\/logistiek-warehouse-medewerker\/\",\"name\":\"Logistiek \/ Warehouse Medewerker - freightned\",\"isPartOf\":{\"@id\":\"https:\/\/freightned.com\/en\/#website\"},\"datePublished\":\"2026-07-13T13:32:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/freightned.com\/vacature\/logistiek-warehouse-medewerker\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/freightned.com\/vacature\/logistiek-warehouse-medewerker\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/freightned.com\/vacature\/logistiek-warehouse-medewerker\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/freightned.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Logistiek \/ Warehouse Medewerker\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/freightned.com\/en\/#website\",\"url\":\"https:\/\/freightned.com\/en\/\",\"name\":\"freightned\",\"description\":\"your flexible logistics partner\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/freightned.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Logistiek \/ Warehouse Medewerker - freightned","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/freightned.com\/nl\/vacature\/logistiek-warehouse-medewerker\/","og_locale":"nl_NL","og_type":"article","og_title":"Logistiek \/ Warehouse Medewerker - freightned","og_description":"Wat ga je doen? Tekst over de vacature.","og_url":"https:\/\/freightned.com\/nl\/vacature\/logistiek-warehouse-medewerker\/","og_site_name":"freightned","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/freightned.com\/vacature\/logistiek-warehouse-medewerker\/","url":"https:\/\/freightned.com\/vacature\/logistiek-warehouse-medewerker\/","name":"Logistiek \/ Warehouse Medewerker - freightned","isPartOf":{"@id":"https:\/\/freightned.com\/en\/#website"},"datePublished":"2026-07-13T13:32:56+00:00","breadcrumb":{"@id":"https:\/\/freightned.com\/vacature\/logistiek-warehouse-medewerker\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/freightned.com\/vacature\/logistiek-warehouse-medewerker\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/freightned.com\/vacature\/logistiek-warehouse-medewerker\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/freightned.com\/"},{"@type":"ListItem","position":2,"name":"Logistiek \/ Warehouse Medewerker"}]},{"@type":"WebSite","@id":"https:\/\/freightned.com\/en\/#website","url":"https:\/\/freightned.com\/en\/","name":"freightned","description":"your flexible logistics partner","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/freightned.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/freightned.com\/nl\/wp-json\/wp\/v2\/vacature\/27024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/freightned.com\/nl\/wp-json\/wp\/v2\/vacature"}],"about":[{"href":"https:\/\/freightned.com\/nl\/wp-json\/wp\/v2\/types\/vacature"}],"wp:attachment":[{"href":"https:\/\/freightned.com\/nl\/wp-json\/wp\/v2\/media?parent=27024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}